{"id":15,"date":"2025-08-04T13:32:17","date_gmt":"2025-08-04T13:32:17","guid":{"rendered":"https:\/\/dummy.xtemos.com\/woodmart2\/pets-elementor\/?page_id=15"},"modified":"2026-03-19T03:40:24","modified_gmt":"2026-03-19T02:40:24","slug":"home-pets","status":"publish","type":"page","link":"https:\/\/pattesdazur.com\/fr\/","title":{"rendered":"Animaux domestiques"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15\" class=\"elementor elementor-15\">\n\t\t\t\t<div class=\"elementor-element elementor-element-208ec4a e-con-full wd-section-stretch e-flex e-con e-parent\" data-id=\"208ec4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0362f77 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"0362f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"617\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477.png\" class=\"attachment-full size-full wp-image-3161\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-400x161.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-1300x522.png 1300w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-768x309.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-18x7.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-430x173.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-700x281.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/Untitled-design-42-e1773874162477-150x60.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7912547 elementor-widget elementor-widget-heading\" data-id=\"7912547\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produits les plus populaires<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a3e94f e-con-full e-flex e-con e-parent\" data-id=\"5a3e94f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c0394e2 e-con-full color-scheme-dark e-flex e-con e-child\" data-id=\"c0394e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ccaae6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"7ccaae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-1200x800.png\" class=\"attachment-large size-large wp-image-3163\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24-150x100.png 150w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_31_24.png 1536w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1818ec6 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"1818ec6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pattesdazur.com\/product-category\/harnais-confort\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53c4527 e-con-full color-scheme-dark e-flex e-con e-child\" data-id=\"53c4527\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38cc026 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"38cc026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-1200x800.png\" class=\"attachment-large size-large wp-image-3164\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36-150x100.png 150w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_30_36.png 1536w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae5954 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"6ae5954\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pattesdazur.com\/product-category\/jouets\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05684eb e-con-full color-scheme-dark e-flex e-con e-child\" data-id=\"05684eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58d627e elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"58d627e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-1200x800.png\" class=\"attachment-large size-large wp-image-3165\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55-150x100.png 150w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_27_55.png 1536w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b63932 elementor-align-center elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"5b63932\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pattesdazur.com\/product-category\/lesses\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-beafbe8 e-flex e-con-boxed e-con e-parent\" data-id=\"beafbe8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-093daaa elementor-widget elementor-widget-spacer\" data-id=\"093daaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-dc19ea0 wd-section-stretch-content e-flex e-con-boxed e-con e-parent\" data-id=\"dc19ea0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3c805 elementor-widget elementor-widget-wd_marquee\" data-id=\"8d3c805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_marquee.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-marquee\">\n\t\t\t<div class=\"wd-marquee-content\">\n\t\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison Personnelle : Monaco, Menton, Nice, Antibes, Cannes\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-paw-2.svg\" title=\"pt-marquise-patte\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison gratuite \u00e0 partir de 70 \u20ac d'achat\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-bone-2.svg\" title=\"pt-marquise-os\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison Personnelle : Monaco, Menton, Nice, Antibes, Cannes\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-paw-2.svg\" title=\"pt-marquise-patte\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison gratuite \u00e0 partir de 70 \u20ac d'achat\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-bone-2.svg\" title=\"pt-marquise-os\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"wd-marquee-content\">\n\t\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison Personnelle : Monaco, Menton, Nice, Antibes, Cannes\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-paw-2.svg\" title=\"pt-marquise-patte\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison gratuite \u00e0 partir de 70 \u20ac d'achat\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-bone-2.svg\" title=\"pt-marquise-os\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison Personnelle : Monaco, Menton, Nice, Antibes, Cannes\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-paw-2.svg\" title=\"pt-marquise-patte\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\tLivraison gratuite \u00e0 partir de 70 \u20ac d'achat\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"wd-marquee-item\">\n\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-marquee-bone-2.svg\" title=\"pt-marquise-os\" loading=\"lazy\" width=\"24\" height=\"24\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-0582c85 e-flex e-con-boxed e-con e-parent\" data-id=\"0582c85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a961ba4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_banner\" data-id=\"a961ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper\">\n\t\t\t<div class=\"promo-banner banner-content-background banner-hover-zoom color-scheme-light banner-btn-size-default banner-btn-style-link wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"600\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-3-opt-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-3-opt-2.jpg 675w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-3-opt-2-430x382.jpg 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-3-opt-2-150x133.jpg 150w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-bottom wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"banner-title wd-fontsize-l\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tLa sant\u00e9 des Dents Avec Oral de la Trousse de Soins.\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pattesdazur.com\/shop\/\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Lien de la banni\u00e8re\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c7084b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_banner\" data-id=\"5c7084b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper\">\n\t\t\t<div class=\"promo-banner banner-default banner-hover-zoom color-scheme-light banner-btn-size-default banner-btn-style-link wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"600\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-4-opt-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-4-opt-2.jpg 690w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-4-opt-2-430x374.jpg 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-4-opt-2-150x130.jpg 150w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-bottom wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"banner-title wd-fontsize-l\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tDes Lits confortables pour Votre Chien\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pattesdazur.com\/shop\/\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Lien de la banni\u00e8re\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36d1570 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_banner\" data-id=\"36d1570\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"promo-banner-wrapper\">\n\t\t\t<div class=\"promo-banner banner-content-background banner-hover-zoom color-scheme-light banner-btn-size-default banner-btn-style-link wd-with-link\">\n\t\t\t\t<div class=\"main-wrapp-img\">\n\t\t\t\t\t<div class=\"banner-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"600\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-5-opt-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-5-opt-2.jpg 675w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-5-opt-2-430x382.jpg 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-banner-dog-5-opt-2-150x133.jpg 150w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wrapper-content-banner wd-fill wd-items-bottom wd-justify-left\">\n\t\t\t\t\t<div class=\"content-banner  text-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"banner-subtitle subtitle-style-background wd-fontsize-xs\" data-elementor-setting-key=\"subtitle\">\n\t\t\t\t\t\t\t\tLivraison gratuite\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"banner-title wd-fontsize-l\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\tPour les commandes \u00e0 partir de 70\u20ac\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pattesdazur.com\/shop\/\" class=\"wd-promo-banner-link wd-fill\" aria-label=\"Lien de la banni\u00e8re\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-e1a4c76 e-flex e-con-boxed e-con e-parent\" data-id=\"e1a4c76\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9b658 elementor-widget elementor-widget-spacer\" data-id=\"3f9b658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09a937f elementor-widget elementor-widget-heading\" data-id=\"09a937f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos packs sp\u00e9ciaux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4181376 elementor-hidden-mobile wd-width-100 wd-nav-accordion-mb-on elementor-widget elementor-widget-wd_product_categories\" data-id=\"4181376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_product_categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-cats-element\">\n\t\t\t\t\t<div class=\"wd-grid-g wd-cats products columns-3 products-bordered-grid-ins wd-products-with-bg elements-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product first\" data-loop=\"1\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/special-pack\/\" aria-label=\"Pack sp\u00e9cial\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack sp\u00e9cial\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/special-pack\/\" aria-label=\"Cat\u00e9gorie de produit special-pack\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product\" data-loop=\"2\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-naturels\/\" aria-label=\"Pack Naturels\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack Naturels\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-naturels\/\" aria-label=\"Cat\u00e9gorie de produit pack-naturels\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product\" data-loop=\"3\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chiens\/\" aria-label=\"Pack Chiens\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack Chiens\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chiens\/\" aria-label=\"Cat\u00e9gorie de produit pack-chiens\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dd267a elementor-hidden-desktop elementor-hidden-tablet wd-width-100 wd-nav-accordion-mb-on elementor-widget elementor-widget-wd_product_categories\" data-id=\"9dd267a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_product_categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-cats-element\">\n\t\t\t\t\t<div class=\"wd-grid-g wd-cats products columns-3 products-bordered-grid-ins wd-products-with-bg elements-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product first\" data-loop=\"1\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/special-pack\/\" aria-label=\"Pack sp\u00e9cial\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-19-mar.-2026-01_44_48-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack sp\u00e9cial\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/special-pack\/\" aria-label=\"Cat\u00e9gorie de produit special-pack\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product\" data-loop=\"2\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-naturels\/\" aria-label=\"Pack Naturels\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_23_16-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack Naturels\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-naturels\/\" aria-label=\"Cat\u00e9gorie de produit pack-naturels\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product\" data-loop=\"3\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chiens\/\" aria-label=\"Pack Chiens\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_31-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tPack Chiens\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chiens\/\" aria-label=\"Cat\u00e9gorie de produit pack-chiens\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-default categories-with-shadow without-product-count product-category product last\" data-loop=\"4\">\n\t\t\t<div class=\"wd-cat-wrap\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chats\/\" aria-label=\"Chats en meute\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-400x267.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-1200x800.png 1200w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-768x512.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-18x12.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-430x287.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-700x467.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-23_22_35-150x100.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tChats en meute\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/pattesdazur.com\/fr\/product-category\/pack-chats\/\" aria-label=\"Cat\u00e9gorie de produit pack-chats\"><\/a>\n\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-234ef16 e-con-full wd-section-stretch e-flex e-con e-parent\" data-id=\"234ef16\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc5ec52 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"fc5ec52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"445\" src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281.png\" class=\"attachment-full size-full wp-image-3162\" alt=\"\" srcset=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281.png 1536w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-400x116.png 400w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-1300x377.png 1300w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-768x223.png 768w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-18x5.png 18w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-430x125.png 430w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-700x203.png 700w, https:\/\/pattesdazur.com\/wp-content\/uploads\/2026\/03\/ChatGPT-Image-18-mar.-2026-21_20_24-e1773874846281-150x43.png 150w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-d19468c e-flex e-con-boxed e-con e-parent\" data-id=\"d19468c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-325411a e-con-full e-flex e-con e-child\" data-id=\"325411a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b91c0 elementor-widget elementor-widget-wd_image_or_svg\" data-id=\"68b91c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_image_or_svg.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wd-image text-right\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-dog-2.svg\" title=\"pt-chien\" loading=\"lazy\" width=\"216\" height=\"200\">\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb37ac1 e-con-full e-flex e-con e-child\" data-id=\"eb37ac1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e67f28 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8e67f28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l wd-underline-colored\">Avec <u>L'amour<\/u><\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-xs\">\n\t\t\t\t\t<p>pour Vos Animaux de compagnie<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-809928b e-con-full e-flex e-con e-child\" data-id=\"809928b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56a5567 elementor-widget elementor-widget-wd_image_or_svg\" data-id=\"56a5567\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_image_or_svg.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wd-image text-left\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\"  src=\"https:\/\/pattesdazur.com\/wp-content\/uploads\/2025\/08\/pt-cat-2.svg\" title=\"pt-chat\" loading=\"lazy\" width=\"251\" height=\"180\">\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Produits les plus populaires Voir Plus Voir Plus Voir Plus Livraison Personnelle : Monaco, Menton, Nice, Antibes, Cannes Livraison gratuite sur commande<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":21,"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":3193,"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/pages\/15\/revisions\/3193"}],"wp:attachment":[{"href":"https:\/\/pattesdazur.com\/fr\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}